{"id":15363,"date":"2018-03-01T13:12:28","date_gmt":"2018-03-01T16:12:28","guid":{"rendered":"https:\/\/www.pagbrasil.com\/?p=15363"},"modified":"2019-11-29T16:18:00","modified_gmt":"2019-11-29T18:18:00","slug":"boleto-flash-aumenta-receita","status":"publish","type":"post","link":"https:\/\/www.pagbrasil.com\/pt-br\/blog\/noticias\/boleto-flash-aumenta-receita\/","title":{"rendered":"O Boleto Flash<sup class='reg'>&reg;<\/sup> tem um papel importante no crescimento da receita das empresas"},"content":{"rendered":"<p>Disponibilizar m\u00e9todos de pagamento adequados \u00e9 uma parte essencial do sucesso de um neg\u00f3cio de e-commerce. No Brasil, existem algumas particularidades que devem ser consideradas: a maioria dos cart\u00f5es de cr\u00e9dito emitidos no pa\u00eds n\u00e3o est\u00e3o habilitados para compras em <a href=\"https:\/\/www.pagbrasil.com\/pt-br\/noticias\/cartao-internacional-moedas-estrangeiras\/\">moeda estrangeira<\/a>, os brasileiros est\u00e3o acostumados a pagar <a href=\"https:\/\/www.pagbrasil.com\/pt-br\/noticias\/tudo-sobre-pagamento-parcelado\/\">parcelado<\/a>, os cart\u00f5es de d\u00e9bito n\u00e3o s\u00e3o muito utilizados no setor de e-commerce apesar de sua popularidade em transa\u00e7\u00f5es presenciais, e o boleto banc\u00e1rio representa quase um quarto de todos os pagamentos no e-commerce.<\/p>\n<p>A escolha dos m\u00e9todos de pagamento disponibilizados no checkout, bem como o provedor de pagamentos, \u00e9 uma tarefa importante. Estas escolhas podem ter um impacto significativo na receita bruta dos neg\u00f3cios. Por exemplo, nossa an\u00e1lise identificou que ao integrar o Boleto Flash<sup class=\"reg\">\u00ae<\/sup> com a PagBrasil em vez do boleto tradicional oferecido pelos bancos brasileiros, \u00e9 poss\u00edvel conseguir um aumento de 10% a 20% em receita bruta.<\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"h3_default\">Por que o Boleto Flash<sup class=\"reg\">\u00ae<\/sup>?<\/h3>\n<p>A forma mais frequente de integrar o boleto banc\u00e1rio como op\u00e7\u00e3o de pagamento \u00e9 faz\u00ea-lo diretamente com os bancos locais. No entanto, existem uma s\u00e9rie de custos indiretos ou ocultos que elevam o pre\u00e7o do processamento de boleto atrav\u00e9s do banco.<\/p>\n<p>Por isso, al\u00e9m da taxa cobrada pelo banco para emiss\u00e3o e processamento, os comerciantes tamb\u00e9m devem ter em conta as despesas indiretas causadas por, entre outras coisas, a reconcilia\u00e7\u00e3o manual (atrav\u00e9s da francesinha), gest\u00e3o manual dos reembolsos, aumento de casos de aten\u00e7\u00e3o ao cliente (motivado pelas baixas taxas de convers\u00e3o) e aumento de canibaliza\u00e7\u00e3o pelo cart\u00e3o de cr\u00e9dito, que tem custos mais altos no que se refere \u00e0s taxas de processamento e tamb\u00e9m mais riscos de chargeback.<\/p>\n<p>Tamb\u00e9m \u00e9 importante destacar que como o boleto foi criado antes do avan\u00e7o do e-commerce, ele n\u00e3o est\u00e1 completamente adaptado \u00e0 ind\u00fastria. Por exemplo, um boleto proporcionado pelo banco n\u00e3o \u00e9 apto para uso in-app, n\u00e3o pode ter o prazo de vencimento ampliado, possui um design n\u00e3o-responsivo, a confirma\u00e7\u00e3o do pagamento pode demorar at\u00e9 tr\u00eas dias \u00fateis e n\u00e3o oferece reembolsos automatizados. Tudo isso leva a baixas taxas de convers\u00e3o. Na m\u00e9dia, somente um de cada dois boletos gerados no pa\u00eds \u00e9 pago.<\/p>\n<p>O Boleto Flash<sup class=\"reg\">\u00ae<\/sup>, da PagBrasil, por outro lado, foi criado com o prop\u00f3sito exclusivo de aumentar as convers\u00f5es. Por isso, de forma predefinida, o Boleto Flash<sup class=\"reg\">\u00ae<\/sup> inclui uma tecnologia responsiva, o que facilita que os compradores possam visualizar e pagar o boleto nos seus dispositivos m\u00f3veis.\u00a0 Al\u00e9m disso, \u00e9 o \u00fanico boleto do pa\u00eds que oferece a confirma\u00e7\u00e3o do pagamento em menos de duas horas.<\/p>\n<p>Ambas caracter\u00edsticas t\u00eam um impacto direto na convers\u00e3o. A primeira delas facilita o processo de checkout para que os compradores tenham uma experi\u00eancia mais flu\u00edda em celulares e tablets, que cada vez mais passam a ser a principal fonte de acesso \u00e0 internet no Brasil. A confirma\u00e7\u00e3o acelerada de pagamento tem um papel importante no sentido de imediatismo observado pelos compradores. Como a compra impulsiva \u00e9 bastante significativa para o e-commerce, quando os consumidores podem pagar e obter acesso r\u00e1pido \u00e0s suas compras, eles estar\u00e3o mais inclinados a finalizar o pagamento.<\/p>\n<p>Como a solu\u00e7\u00e3o de boleto da PagBrasil est\u00e1 otimizada para a ind\u00fastria de e-commerce, os lojistas que ativaram o Boleto Flash<sup class=\"reg\">\u00ae<\/sup> como a op\u00e7\u00e3o de boleto das suas lojas obtiveram um aumento na convers\u00e3o de at\u00e9 10%. Al\u00e9m das caracter\u00edsticas mencionadas anteriormente, a PagBrasil tamb\u00e9m permite ampliar a data de vencimento de forma r\u00e1pida, mesmo ap\u00f3s a emiss\u00e3o do boleto, oferece reembolsos automatizados e uma s\u00e9rie de servi\u00e7os adicionais focados na melhora de convers\u00f5es. Voc\u00ea pode ler mais sobre nossos boletos versus os boletos do banco <a href=\"https:\/\/www.pagbrasil.com\/pt-br\/noticias\/boleto-do-banco-vs-boleto-pagbrasil\/\">aqui<\/a>, e mais sobre como melhorar as convers\u00f5es de boleto <a href=\"https:\/\/www.pagbrasil.com\/pt-br\/noticias\/conversao-de-boletos\/\">aqui<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"h3_default\">Como o Boleto Flash<sup class=\"reg\">\u00ae<\/sup> pode impactar a receita?<\/h3>\n<p>Devido aos custos ocultos do processamento de boletos diretamente com o banco, al\u00e9m das baixas taxas de convers\u00e3o, a receita das empresas pode ver-se afetada. Ao utilizar o Boleto Flash<sup class=\"reg\">\u00ae<\/sup>, os comerciantes observaram resultados positivos na sua receita bruta, com um aumento de 10% a 20% para as transa\u00e7\u00f5es com boleto, o que tem um grande impacto para neg\u00f3cios nos quais os boletos representam uma fra\u00e7\u00e3o significativa os pagamentos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Disponibilizar m\u00e9todos de pagamento adequados \u00e9 uma parte essencial do sucesso de um neg\u00f3cio de e-commerce. No Brasil, existem algumas [&#8230;]<\/p>\n","protected":false},"author":8,"featured_media":52586,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[4],"tags":[],"class_list":["post-15363","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>O Boleto Flash ajuda a aumentar a receita dos neg\u00f3cios<\/title>\n<meta name=\"description\" content=\"Gra\u00e7as ao aumento que proporciona em termos de taxa de convers\u00e3o, o Boleto Flash tem um papel importante no crescimento da receita bruta da empresa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pagbrasil.com\/pt-br\/blog\/noticias\/boleto-flash-aumenta-receita\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O Boleto Flash ajuda a aumentar a receita dos neg\u00f3cios\" \/>\n<meta property=\"og:description\" content=\"Gra\u00e7as ao aumento que proporciona em termos de taxa de convers\u00e3o, o Boleto Flash tem um papel importante no crescimento da receita bruta da empresa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pagbrasil.com\/pt-br\/blog\/noticias\/boleto-flash-aumenta-receita\/\" \/>\n<meta property=\"og:site_name\" content=\"PagBrasil\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pagbrasilpagamentos\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-01T16:12:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-29T18:18:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pagbrasil.com\/wp-content\/uploads\/2018\/03\/boleto-flash-tem-um-papel-importante-no-crescimento-da-receita-das-empresas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1900\" \/>\n\t<meta property=\"og:image:height\" content=\"1700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bianca Lopez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@biancamvickers\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bianca Lopez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.pagbrasil.com\/pt-br\/blog\/noticias\/boleto-flash-aumenta-receita\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.pagbrasil.com\/pt-br\/blog\/noticias\/boleto-flash-aumenta-receita\/\"},\"author\":{\"name\":\"Bianca Lopez\",\"@id\":\"https:\/\/www.pagbrasil.com\/pt-br\/#\/schema\/person\/f1d63f5a18dd6b4c4d67fc7964faf9c4\"},\"headline\":\"O Boleto Flash&reg; tem um papel importante no crescimento da receita das empresas\",\"datePublished\":\"2018-03-01T16:12:28+00:00\",\"dateModified\":\"2019-11-29T18:18:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.pagbrasil.com\/pt-br\/blog\/noticias\/boleto-flash-aumenta-receita\/\"},\"wordCount\":765,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\/\/www.pagbrasil.com\/pt-br\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.pagbrasil.com\/pt-br\/blog\/noticias\/boleto-flash-aumenta-receita\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.pagbrasil.com\/wp-content\/uploads\/2018\/03\/boleto-flash-tem-um-papel-importante-no-crescimento-da-receita-das-empresas.jpg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.pagbrasil.com\/pt-br\/blog\/noticias\/boleto-flash-aumenta-receita\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pagbrasil.com\/pt-br\/blog\/noticias\/boleto-flash-aumenta-receita\/\",\"url\":\"https:\/\/www.pagbrasil.com\/pt-br\/blog\/noticias\/boleto-flash-aumenta-receita\/\",\"name\":\"O Boleto Flash ajuda a aumentar a receita dos neg\u00f3cios\",\"isPartOf\":{\"@id\":\"https:\/\/www.pagbrasil.com\/pt-br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.pagbrasil.com\/pt-br\/blog\/noticias\/boleto-flash-aumenta-receita\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.pagbrasil.com\/pt-br\/blog\/noticias\/boleto-flash-aumenta-receita\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.pagbrasil.com\/wp-content\/uploads\/2018\/03\/boleto-flash-tem-um-papel-importante-no-crescimento-da-receita-das-empresas.jpg\",\"datePublished\":\"2018-03-01T16:12:28+00:00\",\"dateModified\":\"2019-11-29T18:18:00+00:00\",\"description\":\"Gra\u00e7as ao aumento que proporciona em termos de taxa de convers\u00e3o, o Boleto Flash tem um papel importante no crescimento da receita bruta da empresa.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.pagbrasil.com\/pt-br\/blog\/noticias\/boleto-flash-aumenta-receita\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pagbrasil.com\/pt-br\/blog\/noticias\/boleto-flash-aumenta-receita\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pagbrasil.com\/pt-br\/blog\/noticias\/boleto-flash-aumenta-receita\/#primaryimage\",\"url\":\"https:\/\/www.pagbrasil.com\/wp-content\/uploads\/2018\/03\/boleto-flash-tem-um-papel-importante-no-crescimento-da-receita-das-empresas.jpg\",\"contentUrl\":\"https:\/\/www.pagbrasil.com\/wp-content\/uploads\/2018\/03\/boleto-flash-tem-um-papel-importante-no-crescimento-da-receita-das-empresas.jpg\",\"width\":1900,\"height\":1700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.pagbrasil.com\/pt-br\/blog\/noticias\/boleto-flash-aumenta-receita\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.pagbrasil.com\/pt-br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.pagbrasil.com\/pt-br\/blog\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"O Boleto Flash&reg; tem um papel importante no crescimento da receita das empresas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pagbrasil.com\/pt-br\/#website\",\"url\":\"https:\/\/www.pagbrasil.com\/pt-br\/\",\"name\":\"PagBrasil\",\"description\":\"Processe seus pagamentos com PagBrasil, servi\u00e7o de pagamento online de excel\u00eancia para o Brasil, desenvolvido para empresas internacionais.\",\"publisher\":{\"@id\":\"https:\/\/www.pagbrasil.com\/pt-br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pagbrasil.com\/pt-br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.pagbrasil.com\/pt-br\/#organization\",\"name\":\"PagBrasil\",\"url\":\"https:\/\/www.pagbrasil.com\/pt-br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pagbrasil.com\/pt-br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.pagbrasil.com\/wp-content\/uploads\/2023\/03\/logo-PB-2.svg\",\"contentUrl\":\"https:\/\/www.pagbrasil.com\/wp-content\/uploads\/2023\/03\/logo-PB-2.svg\",\"width\":265,\"height\":64,\"caption\":\"PagBrasil\"},\"image\":{\"@id\":\"https:\/\/www.pagbrasil.com\/pt-br\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pagbrasilpagamentos\",\"https:\/\/www.linkedin.com\/company\/pagbrasil-pagamentos-eletronicos-ltda\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pagbrasil.com\/pt-br\/#\/schema\/person\/f1d63f5a18dd6b4c4d67fc7964faf9c4\",\"name\":\"Bianca Lopez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pagbrasil.com\/pt-br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cab62df17d72f0b7796924e5d422973837f7a390cb4aa5f514397fdfb2b6189c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cab62df17d72f0b7796924e5d422973837f7a390cb4aa5f514397fdfb2b6189c?s=96&d=mm&r=g\",\"caption\":\"Bianca Lopez\"},\"sameAs\":[\"https:\/\/x.com\/biancamvickers\"],\"url\":\"https:\/\/www.pagbrasil.com\/pt-br\/blog\/author\/bianca-lopez\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O Boleto Flash ajuda a aumentar a receita dos neg\u00f3cios","description":"Gra\u00e7as ao aumento que proporciona em termos de taxa de convers\u00e3o, o Boleto Flash tem um papel importante no crescimento da receita bruta da empresa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pagbrasil.com\/pt-br\/blog\/noticias\/boleto-flash-aumenta-receita\/","og_locale":"pt_BR","og_type":"article","og_title":"O Boleto Flash ajuda a aumentar a receita dos neg\u00f3cios","og_description":"Gra\u00e7as ao aumento que proporciona em termos de taxa de convers\u00e3o, o Boleto Flash tem um papel importante no crescimento da receita bruta da empresa.","og_url":"https:\/\/www.pagbrasil.com\/pt-br\/blog\/noticias\/boleto-flash-aumenta-receita\/","og_site_name":"PagBrasil","article_publisher":"https:\/\/www.facebook.com\/pagbrasilpagamentos","article_published_time":"2018-03-01T16:12:28+00:00","article_modified_time":"2019-11-29T18:18:00+00:00","og_image":[{"width":1900,"height":1700,"url":"https:\/\/www.pagbrasil.com\/wp-content\/uploads\/2018\/03\/boleto-flash-tem-um-papel-importante-no-crescimento-da-receita-das-empresas.jpg","type":"image\/jpeg"}],"author":"Bianca Lopez","twitter_card":"summary_large_image","twitter_creator":"@biancamvickers","twitter_misc":{"Escrito por":"Bianca Lopez","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.pagbrasil.com\/pt-br\/blog\/noticias\/boleto-flash-aumenta-receita\/#article","isPartOf":{"@id":"https:\/\/www.pagbrasil.com\/pt-br\/blog\/noticias\/boleto-flash-aumenta-receita\/"},"author":{"name":"Bianca Lopez","@id":"https:\/\/www.pagbrasil.com\/pt-br\/#\/schema\/person\/f1d63f5a18dd6b4c4d67fc7964faf9c4"},"headline":"O Boleto Flash&reg; tem um papel importante no crescimento da receita das empresas","datePublished":"2018-03-01T16:12:28+00:00","dateModified":"2019-11-29T18:18:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pagbrasil.com\/pt-br\/blog\/noticias\/boleto-flash-aumenta-receita\/"},"wordCount":765,"commentCount":1,"publisher":{"@id":"https:\/\/www.pagbrasil.com\/pt-br\/#organization"},"image":{"@id":"https:\/\/www.pagbrasil.com\/pt-br\/blog\/noticias\/boleto-flash-aumenta-receita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pagbrasil.com\/wp-content\/uploads\/2018\/03\/boleto-flash-tem-um-papel-importante-no-crescimento-da-receita-das-empresas.jpg","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.pagbrasil.com\/pt-br\/blog\/noticias\/boleto-flash-aumenta-receita\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.pagbrasil.com\/pt-br\/blog\/noticias\/boleto-flash-aumenta-receita\/","url":"https:\/\/www.pagbrasil.com\/pt-br\/blog\/noticias\/boleto-flash-aumenta-receita\/","name":"O Boleto Flash ajuda a aumentar a receita dos neg\u00f3cios","isPartOf":{"@id":"https:\/\/www.pagbrasil.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pagbrasil.com\/pt-br\/blog\/noticias\/boleto-flash-aumenta-receita\/#primaryimage"},"image":{"@id":"https:\/\/www.pagbrasil.com\/pt-br\/blog\/noticias\/boleto-flash-aumenta-receita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pagbrasil.com\/wp-content\/uploads\/2018\/03\/boleto-flash-tem-um-papel-importante-no-crescimento-da-receita-das-empresas.jpg","datePublished":"2018-03-01T16:12:28+00:00","dateModified":"2019-11-29T18:18:00+00:00","description":"Gra\u00e7as ao aumento que proporciona em termos de taxa de convers\u00e3o, o Boleto Flash tem um papel importante no crescimento da receita bruta da empresa.","breadcrumb":{"@id":"https:\/\/www.pagbrasil.com\/pt-br\/blog\/noticias\/boleto-flash-aumenta-receita\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pagbrasil.com\/pt-br\/blog\/noticias\/boleto-flash-aumenta-receita\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pagbrasil.com\/pt-br\/blog\/noticias\/boleto-flash-aumenta-receita\/#primaryimage","url":"https:\/\/www.pagbrasil.com\/wp-content\/uploads\/2018\/03\/boleto-flash-tem-um-papel-importante-no-crescimento-da-receita-das-empresas.jpg","contentUrl":"https:\/\/www.pagbrasil.com\/wp-content\/uploads\/2018\/03\/boleto-flash-tem-um-papel-importante-no-crescimento-da-receita-das-empresas.jpg","width":1900,"height":1700},{"@type":"BreadcrumbList","@id":"https:\/\/www.pagbrasil.com\/pt-br\/blog\/noticias\/boleto-flash-aumenta-receita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pagbrasil.com\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcias","item":"https:\/\/www.pagbrasil.com\/pt-br\/blog\/noticias\/"},{"@type":"ListItem","position":3,"name":"O Boleto Flash&reg; tem um papel importante no crescimento da receita das empresas"}]},{"@type":"WebSite","@id":"https:\/\/www.pagbrasil.com\/pt-br\/#website","url":"https:\/\/www.pagbrasil.com\/pt-br\/","name":"PagBrasil","description":"Processe seus pagamentos com PagBrasil, servi\u00e7o de pagamento online de excel\u00eancia para o Brasil, desenvolvido para empresas internacionais.","publisher":{"@id":"https:\/\/www.pagbrasil.com\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pagbrasil.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.pagbrasil.com\/pt-br\/#organization","name":"PagBrasil","url":"https:\/\/www.pagbrasil.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pagbrasil.com\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/www.pagbrasil.com\/wp-content\/uploads\/2023\/03\/logo-PB-2.svg","contentUrl":"https:\/\/www.pagbrasil.com\/wp-content\/uploads\/2023\/03\/logo-PB-2.svg","width":265,"height":64,"caption":"PagBrasil"},"image":{"@id":"https:\/\/www.pagbrasil.com\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pagbrasilpagamentos","https:\/\/www.linkedin.com\/company\/pagbrasil-pagamentos-eletronicos-ltda\/"]},{"@type":"Person","@id":"https:\/\/www.pagbrasil.com\/pt-br\/#\/schema\/person\/f1d63f5a18dd6b4c4d67fc7964faf9c4","name":"Bianca Lopez","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pagbrasil.com\/pt-br\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cab62df17d72f0b7796924e5d422973837f7a390cb4aa5f514397fdfb2b6189c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cab62df17d72f0b7796924e5d422973837f7a390cb4aa5f514397fdfb2b6189c?s=96&d=mm&r=g","caption":"Bianca Lopez"},"sameAs":["https:\/\/x.com\/biancamvickers"],"url":"https:\/\/www.pagbrasil.com\/pt-br\/blog\/author\/bianca-lopez\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pagbrasil.com\/pt-br\/wp-json\/wp\/v2\/posts\/15363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pagbrasil.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pagbrasil.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pagbrasil.com\/pt-br\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pagbrasil.com\/pt-br\/wp-json\/wp\/v2\/comments?post=15363"}],"version-history":[{"count":5,"href":"https:\/\/www.pagbrasil.com\/pt-br\/wp-json\/wp\/v2\/posts\/15363\/revisions"}],"predecessor-version":[{"id":52589,"href":"https:\/\/www.pagbrasil.com\/pt-br\/wp-json\/wp\/v2\/posts\/15363\/revisions\/52589"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pagbrasil.com\/pt-br\/wp-json\/wp\/v2\/media\/52586"}],"wp:attachment":[{"href":"https:\/\/www.pagbrasil.com\/pt-br\/wp-json\/wp\/v2\/media?parent=15363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pagbrasil.com\/pt-br\/wp-json\/wp\/v2\/categories?post=15363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pagbrasil.com\/pt-br\/wp-json\/wp\/v2\/tags?post=15363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}